{"id":5588,"date":"2016-05-04T08:07:17","date_gmt":"2016-05-04T08:07:17","guid":{"rendered":"http:\/\/www.ayuntamientodeharia.com\/haria\/?p=5588"},"modified":"2016-05-04T08:07:17","modified_gmt":"2016-05-04T08:07:17","slug":"el-ayuntamiento-y-mararia-organizan-talleres-gratuitos-en-el-municipio","status":"publish","type":"post","link":"https:\/\/www.ayuntamientodeharia.com\/haria\/el-ayuntamiento-y-mararia-organizan-talleres-gratuitos-en-el-municipio\/","title":{"rendered":"El Ayuntamiento y Marar\u00eda organizan talleres gratuitos en el municipio"},"content":{"rendered":"<p>La Concejal\u00eda de Servicios Sociales, en colaboraci\u00f3n con la Asociaci\u00f3n Social y Cultural para las Mujeres Marar\u00eda, organiza diferentes talleres gratuitos dirigidos a los vecinos del municipio.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>El 29 de mayo se impartir\u00e1 el taller de \u2018Orientaci\u00f3n laboral: entrevista de trabajo\u2019, de 9:30 a 12:00 horas, en los salones del Centro de la Tercera Edad. Los asistentes aprender\u00e1n c\u00f3mo preparar y comportarse ante una entrevista laboral, as\u00ed c\u00f3mo saber cu\u00e1les son las preguntas m\u00e1s frecuentes a las que deben enfrentarse. Al final de la jornada realizar\u00e1n una simulaci\u00f3n pr\u00e1ctica de una supuesta entrevista. Por otro lado, el mi\u00e9rcoles, 4 de junio, tendr\u00e1 lugar el taller de \u2018Autoestima\u2019, de 18:00 a 19:30 horas, donde se explicar\u00e1 a los asistentes lo que es y los tipos de autoestima que existen, as\u00ed como las pautas que hay que seguir para mejorar la misma.<\/p>\n<p>&nbsp;<\/p>\n<p>Ya el martes, 10 de junio, se realizar\u00e1 el taller \u2018Guateque de la risa\u2019, de 18:00 a 19:30 horas, con el fin de aprender a afrontar los problemas y las emociones de forma optimista y positiva, para disfrutar del presente en plena armon\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>Las personas interesadas en la realizaci\u00f3n de alguno de estos talleres deber\u00e1n inscribirse llamando al 928 836 018, de lunes a jueves, en horario de ma\u00f1ana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Concejal\u00eda de Servicios Sociales, en colaboraci\u00f3n con la Asociaci\u00f3n Social y Cultural para las Mujeres Marar\u00eda, organiza diferentes talleres gratuitos dirigidos a los vecinos del municipio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,11],"tags":[],"class_list":["post-5588","post","type-post","status-publish","format-standard","hentry","category-cultura","category-hoja-de-haria"],"_links":{"self":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/5588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/comments?post=5588"}],"version-history":[{"count":0,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/5588\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media?parent=5588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/categories?post=5588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/tags?post=5588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}