{"id":32661,"date":"2025-06-06T16:11:17","date_gmt":"2025-06-06T15:11:17","guid":{"rendered":"https:\/\/www.ayuntamientodeharia.com\/haria\/?p=32661"},"modified":"2025-06-06T16:11:17","modified_gmt":"2025-06-06T15:11:17","slug":"abierto-el-plazo-de-inscripcion-para-participar-en-la-confeccion-de-alfombras-de-sal-del-corpus-en-haria","status":"publish","type":"post","link":"https:\/\/www.ayuntamientodeharia.com\/haria\/abierto-el-plazo-de-inscripcion-para-participar-en-la-confeccion-de-alfombras-de-sal-del-corpus-en-haria\/","title":{"rendered":"Abierto el plazo de inscripci\u00f3n para participar en la confecci\u00f3n de alfombras de sal del Corpus en Har\u00eda"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El Ayuntamiento de Har\u00eda abre el plazo de inscripci\u00f3n para asociaciones, colectivos y entidades que deseen participar en la tradicional confecci\u00f3n de alfombras de sal, una actividad cultural y religiosa emblem\u00e1tica del municipio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las inscripciones estar\u00e1n abiertas hasta el martes 17 de junio y pueden realizarse de forma presencial, por sede electr\u00f3nica o enviando un correo a <\/span><a href=\"mailto:cultura@ayuntamientodeharia.com\"><span style=\"font-weight: 400;\">cultura@ayuntamientodeharia.com<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Har\u00eda abre el plazo de inscripci\u00f3n para asociaciones, colectivos y entidades que deseen participar en la tradicional confecci\u00f3n de alfombras de sal, una actividad cultural y religiosa emblem\u00e1tica del municipio. Las inscripciones estar\u00e1n abiertas hasta el martes 17 de junio y pueden realizarse de forma presencial, por sede electr\u00f3nica o enviando un [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-32661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festejos"],"_links":{"self":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/32661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/comments?post=32661"}],"version-history":[{"count":1,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/32661\/revisions"}],"predecessor-version":[{"id":32662,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/32661\/revisions\/32662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media\/32655"}],"wp:attachment":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media?parent=32661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/categories?post=32661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/tags?post=32661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}