{"id":32630,"date":"2025-05-23T15:33:04","date_gmt":"2025-05-23T14:33:04","guid":{"rendered":"https:\/\/www.ayuntamientodeharia.com\/haria\/?p=32630"},"modified":"2025-05-23T15:33:04","modified_gmt":"2025-05-23T14:33:04","slug":"explora-los-secretos-del-fondo-marino-en-una-experiencia-unica-en-haria","status":"publish","type":"post","link":"https:\/\/www.ayuntamientodeharia.com\/haria\/explora-los-secretos-del-fondo-marino-en-una-experiencia-unica-en-haria\/","title":{"rendered":"Explora los secretos del fondo marino en una experiencia \u00fanica en Har\u00eda"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Este domingo, 25 de mayo, a las 11:00 horas, el Centro Socio Cultural de Calet\u00f3n Blanco, en \u00d3rzola, acoge una actividad especial con motivo del D\u00eda Internacional de la Red Natura 2000. Enmarcada en el proyecto Life Insular y organizada por el Organismo Aut\u00f3nomo de Parques Nacionales, esta jornada nos invita a sumergirnos en la biodiversidad marina de Lanzarote y La Graciosa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La entidad Innoceana ofrecer\u00e1 una charla divulgativa sobre los sebadales, praderas submarinas esenciales para el equilibrio ecol\u00f3gico, acompa\u00f1ada de una experiencia inmersiva con gafas 3D. Adem\u00e1s, se proyectar\u00e1 el documental \u2018Jardines de la penumbra\u2019, que muestra la belleza y vulnerabilidad de los corales de las costas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las plazas son limitadas. Las personas interesadas pueden reservar su entrada a trav\u00e9s de la web <\/span><a href=\"https:\/\/www.inscribirme.com\/entre-praderas-y-corales\"><span style=\"font-weight: 400;\">https:\/\/www.inscribirme.com\/entre-praderas-y-corales<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo, 25 de mayo, a las 11:00 horas, el Centro Socio Cultural de Calet\u00f3n Blanco, en \u00d3rzola, acoge una actividad especial con motivo del D\u00eda Internacional de la Red Natura 2000. Enmarcada en el proyecto Life Insular y organizada por el Organismo Aut\u00f3nomo de Parques Nacionales, esta jornada nos invita a sumergirnos en la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":32631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-32630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion"],"_links":{"self":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/32630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/comments?post=32630"}],"version-history":[{"count":1,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/32630\/revisions"}],"predecessor-version":[{"id":32632,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/32630\/revisions\/32632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media\/32631"}],"wp:attachment":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media?parent=32630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/categories?post=32630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/tags?post=32630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}