{"id":2710,"date":"2015-10-24T22:08:31","date_gmt":"2015-10-24T22:08:31","guid":{"rendered":"http:\/\/www.ayuntamientodeharia.com\/haria\/?p=2710"},"modified":"2015-10-24T22:08:31","modified_gmt":"2015-10-24T22:08:31","slug":"el-consistorio-enarbola-la-bandera-nacional-de-canarias-con-motivo-de-su-51-aniversario","status":"publish","type":"post","link":"https:\/\/www.ayuntamientodeharia.com\/haria\/el-consistorio-enarbola-la-bandera-nacional-de-canarias-con-motivo-de-su-51-aniversario\/","title":{"rendered":"El Consistorio enarbola  la bandera nacional de  Canarias con motivo de  su 51 aniversario"},"content":{"rendered":"<p><strong> La moci\u00f3n fue aprobada este viernes en sesi\u00f3n plenaria<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/10\/bandera.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2678\" src=\"http:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/10\/bandera-300x285.jpg\" alt=\"bandera\" width=\"300\" height=\"285\" srcset=\"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/10\/bandera-300x285.jpg 300w, https:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/10\/bandera.jpg 647w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El Pleno del Ayuntamiento de Har\u00eda, reunido en sesi\u00f3n extraordinaria, aprob\u00f3 este viernes, con ocho votos a favor y uno en contra, una moci\u00f3n en relaci\u00f3n a la conmemoraci\u00f3n de la creaci\u00f3n de la bandera nacional de Canarias.<\/p>\n<p>&nbsp;<br \/>\nAs\u00ed, la Corporaci\u00f3n municipal acord\u00f3 reconocer a la bandera nacional de Canarias, blanca, azul y amarilla, con siete estrellas verdes, como uno de los s\u00edmbolos colectivos del Pueblo Canario, \u201cexpresi\u00f3n de las aspiraciones de libertad, hermandad y progreso de las gentes de las ocho islas, as\u00ed como de los canarios y canarias del exterior, al igual que el leg\u00edtimo derecho de nuestro pueblo a decidir su futuro en libertad\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><br \/>\nA la finalizaci\u00f3n del Pleno, los concejales del grupo de gobierno izaron la bandera en uno de los laterales de la fachada de la sede consistorial, que ondear\u00e1 durante la semana del 22 de octubre del presente a\u00f1o, con motivo de su 51 aniversario.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La moci\u00f3n fue aprobada este viernes en sesi\u00f3n plenaria &nbsp; El Pleno del Ayuntamiento de Har\u00eda, reunido en sesi\u00f3n extraordinaria, aprob\u00f3 este viernes, con ocho votos a favor y uno en contra, una moci\u00f3n en relaci\u00f3n a la conmemoraci\u00f3n de la creaci\u00f3n de la bandera nacional de Canarias. &nbsp; As\u00ed, la Corporaci\u00f3n municipal acord\u00f3 reconocer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2710","post","type-post","status-publish","format-standard","hentry","category-hoja-de-haria"],"_links":{"self":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/2710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/comments?post=2710"}],"version-history":[{"count":0,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/2710\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media?parent=2710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/categories?post=2710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/tags?post=2710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}