{"id":2369,"date":"2015-09-04T11:01:16","date_gmt":"2015-09-04T11:01:16","guid":{"rendered":"http:\/\/www.ayuntamientodeharia.com\/haria\/?p=2369"},"modified":"2015-09-04T11:01:16","modified_gmt":"2015-09-04T11:01:16","slug":"lionel-morales-campeon-de-espana-de-paratriatlon-2015","status":"publish","type":"post","link":"https:\/\/www.ayuntamientodeharia.com\/haria\/lionel-morales-campeon-de-espana-de-paratriatlon-2015\/","title":{"rendered":"Lionel Morales, campe\u00f3n de Espa\u00f1a de Paratriatl\u00f3n 2015"},"content":{"rendered":"<p><a href=\"http:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/09\/lionel.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-2356\" src=\"http:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/09\/lionel-300x210.jpg\" alt=\"lionel\" width=\"300\" height=\"210\" srcset=\"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/09\/lionel-300x210.jpg 300w, https:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/09\/lionel-1024x719.jpg 1024w, https:\/\/www.ayuntamientodeharia.com\/haria\/wp-content\/uploads\/2015\/09\/lionel.jpg 1169w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El pasado s\u00e1bado, Lionel Morales demostr\u00f3 ser uno de los mejores deportistas espa\u00f1oles de la categor\u00eda PT2, ya que domin\u00f3 de principio a fin el \u2018Campeonato de Espa\u00f1a de Paratriatl\u00f3n de Altafulla\u2019, cruzando la l\u00ednea de meta como primer clasificado y con una gran diferencia respecto al resto de participantes.<\/p>\n<p>&nbsp;<\/p>\n<p>En el segmento de la nataci\u00f3n, complet\u00f3 el recorrido de 750 metros en un tiempo de 12 minutos y 40 segundos. Lionel sal\u00eda del agua en segunda posici\u00f3n detr\u00e1s de Ander Romarate, pero fue en el segmento de la bicicleta donde se hizo con el liderato de la prueba. En esta parte, complet\u00f3 los 20 kil\u00f3metros en un tiempo de 40 minutos y 18 segundos. Posteriormente, cruzar\u00eda la l\u00ednea de meta como ganador de la prueba haciendo 5 kil\u00f3metros a pie con un tiempo de 24 minutos y 14 segundos.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde el Ayuntamiento de Har\u00eda queremos felicitar a Lionel Morales por su nuevo \u00e9xito conseguido en el \u2018Campeonato de Espa\u00f1a de Paratriatl\u00f3n de Altafulla\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado, Lionel Morales demostr\u00f3 ser uno de los mejores deportistas espa\u00f1oles de la categor\u00eda PT2, ya que domin\u00f3 de principio a fin el \u2018Campeonato de Espa\u00f1a de Paratriatl\u00f3n de Altafulla\u2019, cruzando la l\u00ednea de meta como primer clasificado y con una gran diferencia respecto al resto de participantes. &nbsp; En el segmento de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,11],"tags":[],"class_list":["post-2369","post","type-post","status-publish","format-standard","hentry","category-deportes","category-hoja-de-haria"],"_links":{"self":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/2369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/comments?post=2369"}],"version-history":[{"count":0,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/posts\/2369\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/media?parent=2369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/categories?post=2369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ayuntamientodeharia.com\/haria\/wp-json\/wp\/v2\/tags?post=2369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}